{"id":19757,"date":"2021-02-01T15:19:30","date_gmt":"2021-02-01T14:19:30","guid":{"rendered":"https:\/\/www.gruppofabbri.com\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/"},"modified":"2025-08-29T09:36:40","modified_gmt":"2025-08-29T07:36:40","slug":"automac-55-piu","status":"publish","type":"page","link":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/","title":{"rendered":"Automac 55 Pi\u00f9"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;90px&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ffffff&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;2%&#8220; bottom_padding=&#8220;2%&#8220; top_padding_tablet=&#8220;8%&#8220; bottom_padding_tablet=&#8220;8%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; id=&#8220;home&#8220; overlay_strength=&#8220;0.5&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;straight_section&#8220;][vc_column column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;no-extra-padding&#8220; column_padding_phone=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;right&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; zindex=&#8220;100&#8243; gradient_direction=&#8220;left_t_to_right_b&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;3\/5&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220; offset=&#8220;vc_col-xs-12&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; min_width=&#8220;47vh&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;product-column-first-section&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; enable_border_animation=&#8220;true&#8220; bg_image_animation=&#8220;none&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220;][nectar_animated_title heading_tag=&#8220;h1&#8243; style=&#8220;hinge-drop&#8220; color=&#8220;Accent-Color&#8220; text=&#8220;Automac 55 Pi\u00f9&#8220;][image_with_animation image_url=&#8220;9516&#8243; animation=&#8220;Fade In&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][vc_column_text css=&#8220;.vc_custom_1633613414451{margin-top: 30px !important;}&#8220; el_class=&#8220;subtitle_icon_product&#8220;]\n<p style=\"text-align: left;\">Stretch<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;.vc_custom_1648447901408{margin-top: 30px !important;}&#8220;]Die automatische Stretchverpackungsmaschine Automac 55 Pi\u00f9 bietet beste Leistungen in Bezug auf Zuverl\u00e4ssigkeit, Geschwindigkeit (bis zu 55 ppm, mit einstellbaren Parametern je nach den spezifischen Produktionsanforderungen) und Aussehen des verpackten Produkts und passt perfekt in die Verpackungszentren f\u00fcr frische und ultrafrische Lebensmittel, die eine hohe Stundenleistung erfordern.<\/p>\n<p>Die Geschwindigkeitsregelung erm\u00f6glicht die Anpassung der Maschine an eine Vielzahl von Produkttypen, und wenn keine Schalen auf der Zuf\u00fchrung vorhanden sind oder diese nur sporadisch ankommen, stoppt die Maschine automatisch alle Bewegungen und bleibt im Standby-Modus. Dadurch wird der Stromverbrauch drastisch gesenkt und die mechanische Abnutzung minimiert, so dass Sie den Verbrauch und die Wartung reduzieren und gleichzeitig die Umwelt sch\u00fctzen k\u00f6nnen.<\/p>\n<p>Automac 55 Pi\u00f9 verpackt alle Lebensmittel, die mit der Stretch-Technologie kompatibel sind, mit neutraler oder bedruckter Stretch-Folie: wei\u00dfes und rotes Fleisch, Schweinefleisch, Fisch, K\u00e4se, Obst, Gem\u00fcse&#8230; Die Verwendung von bedruckter Folie tr\u00e4gt dazu bei, das Erscheinungsbild der verpackten Lebensmittel zu verbessern oder aufzuwerten, und macht sie so attraktiver, wenn sie am Verkaufsort pr\u00e4sentiert werden.<br \/>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.5&#8243; width=&#8220;2\/5&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220; offset=&#8220;vc_col-xs-12&#8243;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; min_width_desktop=&#8220;43vw&#8220; min_width_tablet=&#8220;50vw&#8220; min_width_phone=&#8220;50vw&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;15491&#8243; background_image_position=&#8220;center center&#8220; enable_bg_scale=&#8220;true&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.5&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;ro-reveal-from-right&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;80vh&#8220; custom_height_tablet=&#8220;40vh&#8220; custom_height_phone=&#8220;300px&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ffffff&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;3%&#8220; bottom_padding=&#8220;2%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.5&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;product-column-features&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_column_text css=&#8220;.vc_custom_1648447945496{margin-top: 30px !important;}&#8220;]Dank der langj\u00e4hrigen Erfahrung der Fabbri Group in der Herstellung von Verpackungsmaschinen und Lebensmittelfolien liefert die Automac 55 Pi\u00f9 maximale Ergebnisse in Kombination mit Folien der Fabbri Group, kann aber auch mit denen aller anderen gro\u00dfen Hersteller auf dem Markt hervorragende Leistungen erbringen.<\/p>\n<p>Automac 55 Pi\u00f9 garantiert au\u00dferdem eine hervorragende Verpackung mit jeder Art von Tray, unabh\u00e4ngig von den folgenden Parametern:<br \/>\n&#8211; Material (Schalen aus expandiertem Polystyrol, starren, pflanzlichen oder kompostierbaren Materialien)<br \/>\n&#8211; Form und Gr\u00f6\u00dfe (kleine Catering-Tabletts oder gro\u00dfe Tabletts)<br \/>\n&#8211; Farbe (farbige oder transparente Tabletts)<\/p>\n<p>Um einen maximalen Schutz und Erhalt des Produkts zu gew\u00e4hrleisten, widmet Automac 55 Pi\u00f9 der Versiegelung der Folie unter der Schale besondere Aufmerksamkeit: Das Versiegelungsband am Auslauf ist so konzipiert, dass die Folie optimal versiegelt wird, ohne dass es zu einer \u00dcberhitzung der Schale oder des Produkts kommt.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_column_text]\n<p style=\"text-align: center;\"><iframe style=\"display: block; margin: 0 auto;\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-cookieconsent=\"marketing\" data-cookieblock-src=\"https:\/\/www.youtube-nocookie.com\/embed\/l3e9IRE3BYg?rel=0&amp;modestbranding=1&amp;showinfo=0\"><\/iframe><\/p>\n[\/vc_column_text][vc_column_text]\n<p style=\"text-align: center;\"><iframe style=\"display: block; margin: 0 auto;\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-cookieconsent=\"marketing\" data-cookieblock-src=\"https:\/\/www.youtube-nocookie.com\/embed\/PReryUBYjtU?rel=0&amp;modestbranding=1&amp;showinfo=0\"><\/iframe><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;7%&#8220; bottom_padding=&#8220;7%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; class=&#8220;row_faq_film&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][nectar_animated_title heading_tag=&#8220;h2&#8243; style=&#8220;color-strip-reveal&#8220; color=&#8220;Accent-Color&#8220; text=&#8220;Merkmale des Automac 55 Pi\u00f9&#8220;][toggles style=&#8220;minimal&#8220; accordion=&#8220;true&#8220;][toggle color=&#8220;Default&#8220; title=&#8220;Einfache Inline-Installation.&#8220;][vc_custom_heading text=&#8220;Die Robustheit, Zuverl\u00e4ssigkeit, Flexibilit\u00e4t und einfache Integration der Maschine machen sie zur idealen Maschine f\u00fcr hohe Produktivit\u00e4t. Die Maschine f\u00fchrt die unregelm\u00e4\u00dfig ankommenden Schalen zu und f\u00fcgt sich so direkt in die Linie ein, ohne die Hilfe von Kadenzb\u00e4ndern.&#8220; font_container=&#8220;tag:p|text_align:left|color:rgba(10%2C10%2C10%2C0.65)&#8220; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][\/toggle][toggle color=&#8220;Default&#8220; title=&#8220;Bedienfeld mit Farb-Touch-Screen-Monitor.&#8220;][vc_custom_heading text=&#8220;Der Monitor liefert alle Arten von Informationen mit einer benutzerfreundlichen Oberfl\u00e4che. Die Automac 55 Pi\u00f9 kann bis zu 29 Wickelprogramme verwalten und garantiert eine individuelle Programmierung, an die keine andere Wickelmaschine herankommt. Das in die Schalttafel integrierte Diagnosesystem gew\u00e4hrleistet eine vollst\u00e4ndige Kontrolle der Maschine und erm\u00f6glicht eine schnelle Erkennung von Anomalien.&#8220; font_container=&#8220;tag:p|text_align:left|color:rgba(10%2C10%2C10%2C0.65)&#8220; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][\/toggle][toggle color=&#8220;Default&#8220; title=&#8220;Schneller Rollenwechsel.&#8220;][vc_custom_heading text=&#8220;Beim Automac 55 Pi\u00f9 kann die Folienrolle in nur 45\u201d gewechselt werden, so dass die Produktion fast sofort wieder aufgenommen werden kann. Mit der optionalen \u201cSecond reel support\u201d kann diese Zeit sogar auf weniger als 30\u201d verk\u00fcrzt werden. Neben der Konfiguration des Wicklers erleichtert auch das geringere Gewicht der von der Fabbri Group hergestellten Stretchfolienrollen, die stets ein optimales Verh\u00e4ltnis zwischen Dicke und Leistung aufweisen und somit Einsparungen und Vorteile f\u00fcr die Umwelt mit sich bringen, den Austausch.&#8220; font_container=&#8220;tag:p|text_align:left|color:rgba(10%2C10%2C10%2C0.65)&#8220; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][\/toggle][toggle color=&#8220;Default&#8220; title=&#8220;Zubeh\u00f6r und Optionen.&#8220;][vc_custom_heading text=&#8220;Der Automac 55 Pi\u00f9 kann mit Einlaufverl\u00e4ngerungen und Auslaufrollenbahnen ausgestattet werden, die eine optimale Integration in die Zuf\u00fchr- und Entnahmesysteme der Schalen erm\u00f6glichen. Es ist auch m\u00f6glich, Automac 55 Pi\u00f9 mit Fotozellen und Anschl\u00fcssen auszustatten, um ein optimales Zusammenspiel mit Portioniermaschinen und Preisauszeichnungswaagen zu gew\u00e4hrleisten.&#8220; font_container=&#8220;tag:p|text_align:center|color:rgba(10%2C10%2C10%2C0.65)&#8220; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][\/toggle][toggle color=&#8220;Default&#8220; title=&#8220;Optimales Verh\u00e4ltnis zwischen Leistung und Verbrauch.&#8220;][vc_custom_heading text=&#8220;Bei Abwesenheit des Produkts schaltet sich der Automac 55 Pi\u00f9 automatisch ab, wodurch der Verbrauch drastisch gesenkt wird und der Verschlei\u00df im Laufe der Zeit erkennbar ist.&#8220; font_container=&#8220;tag:p|text_align:left|color:rgba(10%2C10%2C10%2C0.65)&#8220; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][\/toggle][toggle color=&#8220;Default&#8220; title=&#8220;Es wird keine Druckluft ben\u00f6tigt.&#8220;][vc_custom_heading text=&#8220;Alle Antriebe des Automac 55 Pi\u00f9 sind elektrisch: Es wird keine Druckluft ben\u00f6tigt und es gibt keine Kompressoren an Bord der Maschine.&#8220; font_container=&#8220;tag:p|text_align:left|color:rgba(10%2C10%2C10%2C0.65)&#8220; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][\/toggle][toggle color=&#8220;Default&#8220; title=&#8220;Maximale Sicherheit f\u00fcr den Bediener.&#8220;][vc_custom_heading text=&#8220;Bewegliche, hei\u00dfe oder scharfe Teile sind durch Sicherheitsvorrichtungen gesch\u00fctzt, die nicht umgangen werden k\u00f6nnen und daher unzug\u00e4nglich bleiben.&#8220; font_container=&#8220;tag:p|text_align:left|color:rgba(10%2C10%2C10%2C0.65)&#8220; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][\/toggle][toggle color=&#8220;Default&#8220; title=&#8220;Ein Lieferant f\u00fcr das gesamte Verpackungssystem.&#8220;][vc_custom_heading text=&#8220;Automac 55 Pi\u00f9 ist Teil einer vollst\u00e4ndig integrierten L\u00f6sung, die von der Fabbri Group angeboten wird, einem einzigen Partner f\u00fcr Maschinen, Software, Folien, technische Unterst\u00fctzung und Ersatzteile.&#8220; font_container=&#8220;tag:p|text_align:left|color:rgba(10%2C10%2C10%2C0.65)&#8220; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeInUp&#8220;][\/toggle][\/toggles][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#f9f9f9&#8243; scene_position=&#8220;center&#8220; bottom_padding=&#8220;3%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_gallery type=&#8220;flickity_style&#8220; images=&#8220;9482,13724,9432,13191,13207,13375,13223&#8243; flickity_spacing=&#8220;default&#8220; flickity_controls=&#8220;material_pagination&#8220; flickity_overflow=&#8220;hidden&#8220; flickity_wrap_around=&#8220;wrap&#8220; flickity_desktop_columns=&#8220;1&#8243; flickity_small_desktop_columns=&#8220;1&#8243; flickity_tablet_columns=&#8220;1&#8243; flickity_box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; onclick=&#8220;link_no&#8220; img_size=&#8220;full&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;2%&#8220; bottom_padding=&#8220;3%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; el_class=&#8220;product-column-images&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_column_text]\n<p style=\"text-align: center;\">Testen Sie den Automac 55 Pi\u00f9 mit den folgenden Fabbri Group-Folien:<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; class=&#8220;row_to_move&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;14018&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/film-e-pellicole\/film-stretch\/koex\/&#8220;]\n<h3><strong>Koex<\/strong><\/h3>\n<div class=\"wrap_description_box\">Die ideale PVC-basierte Folie f\u00fcr alle Arten von Lebensmitteln. Erh\u00e4ltlich in neutraler und gedruckter Form.<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;14010&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/film-e-pellicole\/film-stretch\/fungustar\/&#8220;]\n<h3><strong>Fungustar<\/strong><\/h3>\n<div class=\"wrap_description_box Il film a base\">Folie auf PVC-Basis, die speziell f\u00fcr die Verpackung von Pilzen hergestellt wird. Druckbar.<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;14060&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/film-e-pellicole\/film-stretch\/pex\/&#8220;]\n<h3><strong>PEX<\/strong><\/h3>\n<div class=\"wrap_description_box Il film a base\">Die ideale Folie auf PE-Basis f\u00fcr alle Arten von Lebensmitteln. Erh\u00e4ltlich in neutraler und gedruckter Form.<\/div>\n[\/fancy_box][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;14056&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/film-e-pellicole\/film-stretch\/pexy\/&#8220;]\n<h3><strong>Pexy<\/strong><\/h3>\n<div class=\"wrap_description_box Il film a base\">Die PE-basierte Folie ist ideal f\u00fcr fettreiche Lebensmittel und die Lagerung bei niedrigen Temperaturen.<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;14028&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/film-e-pellicole\/pellicole-compostabili-biobased\/biobased-star-film\/&#8220;]\n<h3><strong>Biobased Star Film<\/strong><\/h3>\n<div class=\"wrap_description_box Il film a base\">\n<p>&#8222;OK-biobased<sup>\u00ae<\/sup>&#8222;-zertifizierte Stretchfolie vom T\u00dcV Austria. Druckbar.<\/p>\n<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;14052&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/film-e-pellicole\/pellicole-compostabili-biobased\/nature-fresh\/&#8220;]\n<h3><strong>Nature Fresh<\/strong><\/h3>\n<div class=\"wrap_description_box Il film a base\">Die zertifizierte kompostierbare Folie f\u00fcr die automatische und manuelle Verpackung aller Arten von Lebensmitteln. Druckbar. Auch erh\u00e4ltlich in Cutterboxen f\u00fcr Ho.Re.Ca.<\/div>\n[\/fancy_box][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; bottom_padding=&#8220;3%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; centered_text=&#8220;true&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][nectar_btn size=&#8220;jumbo&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;fontawesome&#8220; text=&#8220;Kontakt&#8220; url=&#8220;\/de\/contatti\/&#8220; icon_fontawesome=&#8220;fa fa-envelope&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;90px&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ffffff&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;2%&#8220; bottom_padding=&#8220;2%&#8220; top_padding_tablet=&#8220;8%&#8220; bottom_padding_tablet=&#8220;8%&#8220;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":12718,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-19757","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Industrielle Verpackung mit anpassbarer Geschwindigkeit<\/title>\n<meta name=\"description\" content=\"Automac 55 Plus ist eine einstellbare Wickelmaschine bis 55 ppm, ideal f\u00fcr unterschiedliche Produkte und Produktionsprozesse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Industrielle Verpackung mit anpassbarer Geschwindigkeit\" \/>\n<meta property=\"og:description\" content=\"Automac 55 Plus ist eine einstellbare Wickelmaschine bis 55 ppm, ideal f\u00fcr unterschiedliche Produkte und Produktionsprozesse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Fabbri | Official WebSite\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T07:36:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/verpackungsmaschinen\\\/automatische-stretchverpackungsmaschinen\\\/automac-55-piu\\\/\",\"url\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/verpackungsmaschinen\\\/automatische-stretchverpackungsmaschinen\\\/automac-55-piu\\\/\",\"name\":\"Industrielle Verpackung mit anpassbarer Geschwindigkeit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/#website\"},\"datePublished\":\"2021-02-01T14:19:30+00:00\",\"dateModified\":\"2025-08-29T07:36:40+00:00\",\"description\":\"Automac 55 Plus ist eine einstellbare Wickelmaschine bis 55 ppm, ideal f\u00fcr unterschiedliche Produkte und Produktionsprozesse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/verpackungsmaschinen\\\/automatische-stretchverpackungsmaschinen\\\/automac-55-piu\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/verpackungsmaschinen\\\/automatische-stretchverpackungsmaschinen\\\/automac-55-piu\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/verpackungsmaschinen\\\/automatische-stretchverpackungsmaschinen\\\/automac-55-piu\\\/#breadcrumb\",\"itemListElement\":[]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/\",\"name\":\"Gruppo Fabbri | Official WebSite\",\"description\":\"Macchine e Film per l&#039;imballaggio e confezionamento alimentare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Industrielle Verpackung mit anpassbarer Geschwindigkeit","description":"Automac 55 Plus ist eine einstellbare Wickelmaschine bis 55 ppm, ideal f\u00fcr unterschiedliche Produkte und Produktionsprozesse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/","og_locale":"de_DE","og_type":"article","og_title":"Industrielle Verpackung mit anpassbarer Geschwindigkeit","og_description":"Automac 55 Plus ist eine einstellbare Wickelmaschine bis 55 ppm, ideal f\u00fcr unterschiedliche Produkte und Produktionsprozesse.","og_url":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/","og_site_name":"Gruppo Fabbri | Official WebSite","article_modified_time":"2025-08-29T07:36:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/","url":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/","name":"Industrielle Verpackung mit anpassbarer Geschwindigkeit","isPartOf":{"@id":"https:\/\/www.gruppofabbri.com\/de\/#website"},"datePublished":"2021-02-01T14:19:30+00:00","dateModified":"2025-08-29T07:36:40+00:00","description":"Automac 55 Plus ist eine einstellbare Wickelmaschine bis 55 ppm, ideal f\u00fcr unterschiedliche Produkte und Produktionsprozesse.","breadcrumb":{"@id":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/automac-55-piu\/#breadcrumb","itemListElement":[]},{"@type":"WebSite","@id":"https:\/\/www.gruppofabbri.com\/de\/#website","url":"https:\/\/www.gruppofabbri.com\/de\/","name":"Gruppo Fabbri | Official WebSite","description":"Macchine e Film per l&#039;imballaggio e confezionamento alimentare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gruppofabbri.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/19757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/comments?post=19757"}],"version-history":[{"count":3,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/19757\/revisions"}],"predecessor-version":[{"id":30224,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/19757\/revisions\/30224"}],"up":[{"embeddable":true,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/12718"}],"wp:attachment":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/media?parent=19757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}