{"id":12718,"date":"2021-06-04T16:52:39","date_gmt":"2021-06-04T14:52:39","guid":{"rendered":"https:\/\/www.gruppofabbri.com\/produkte\/verpackungsmaschinen\/avvolgitrici-automatiche\/"},"modified":"2025-08-29T09:49:43","modified_gmt":"2025-08-29T07:49:43","slug":"automatische-stretchverpackungsmaschinen","status":"publish","type":"page","link":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/","title":{"rendered":"Automatische Stretchverpackungsmaschinen"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;10826&#8243; bg_position=&#8220;left center&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;10%&#8220; bottom_padding=&#8220;10%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#012169&#8243; overlay_strength=&#8220;1&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; parallax_bg=&#8220;true&#8220; parallax_bg_speed=&#8220;fast&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/12&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][nectar_highlighted_text color_type=&#8220;regular&#8220; highlight_color=&#8220;#1dafec&#8220; style=&#8220;half_text&#8220; custom_font_size=&#8220;48px&#8220;]\n<h1>Automatische <em>Stretchverpackungsmaschinen<\/em><\/h1>\n[\/nectar_highlighted_text][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8220;Full Width Line&#8220; line_thickness=&#8220;1&#8243; divider_color=&#8220;default&#8220; custom_height=&#8220;100&#8243;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;7\/12&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;40px&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; centered_text=&#8220;true&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_custom_heading text=&#8220;Entdecken Sie unsere automatische Stretchverpackungsmaschinen&#8220; font_container=&#8220;tag:h3|text_align:center&#8220; use_theme_fonts=&#8220;yes&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; id=&#8220;row_nav_intern&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; centered_text=&#8220;true&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;7335&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;#row_elixa&#8220;]\n<h2><\/h2>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; centered_text=&#8220;true&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;7336&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;#row_automac&#8220;]\n<h2><\/h2>\n[\/fancy_box][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ffffff&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; id=&#8220;row_elixa&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-10-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color=&#8220;#f4f4f4&#8243; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220;][nectar_animated_title heading_tag=&#8220;h2&#8243; style=&#8220;hinge-drop&#8220; color=&#8220;Accent-Color&#8220; text=&#8220;Elixa\u00ae-Verpackungsmaschinen&#8220;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8220;.vc_custom_1720022684419{margin-top: 30px !important;}&#8220;]Elixa\u00ae-Verpackungsmaschinen sind vollautomatisch, zuverl\u00e4ssig und verf\u00fcgen \u00fcber ein damals patentiertes 4-Wege-Folienstretching-System, das in Verbindung mit der automatischen Erkennung des Produktformats denjenigen, die Produkte mit sehr unterschiedlichen Formaten verpacken m\u00fcssen und daher maximale Flexibilit\u00e4t ben\u00f6tigen, maximale Vorteile bietet und weltweit einzigartig ist.<\/p>\n<p>Die Elixa\u00ae-Super-Stretch-Technologie erm\u00f6glicht es, jede Art von Schale und Lebensmittel mit einer einzigen Folienrolle zu verpacken, was erhebliche Vorteile in Bezug auf Management und Kosteneinsparungen mit sich bringt. Die vollautomatischen und kompakten Elixa\u00ae- Verpackungsmaschinen sind die beste L\u00f6sung f\u00fcr mittlere Produktivit\u00e4t und Arbeitsumgebungen, in denen der Platz knapp ist.<\/p>\n<p>Sie werden besonders in Supermarktabteilungen wie Metzgereien, Gefl\u00fcgel- und Fischgesch\u00e4ften, Feinkostl\u00e4den, Obst-und Gem\u00fcsegesch\u00e4ften, aber auch in der Industrie gesch\u00e4tzt.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;14827&#8243; background_image_position=&#8220;center center&#8220; enable_bg_scale=&#8220;true&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;25592&#8243; background_image_position=&#8220;center center&#8220; enable_bg_scale=&#8220;true&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-10-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220;][vc_column_text css=&#8220;.vc_custom_1734443559374{margin-top: 30px !important;}&#8220;]Dank der langj\u00e4hrigen Erfahrung der Gruppo Fabbri in der Herstellung von Verpackungsmaschinen und Lebensmittelfolien erm\u00f6glicht die Verpackung von frischen und ultrafrischen Lebensmitteln mit Elixa\u00ae-Verpackungsmaschinen in Kombination mit Gruppo Fabbri-Stretchfolien den Schutz und die<br \/>\nKonservierung von Lebensmitteln bei gleichzeitiger Optimierung der eingesetzten Materialmenge. Die Maschinen der Elixa\u00ae-Reihe erzielen aber auch mit den wichtigsten auf dem Markt erh\u00e4ltlichen Stretchfolien optimale Verpackungsergebnisse.<\/p>\n<p>Die Elixa\u00ae-Maschinen sind mit Baus\u00e4tzen f\u00fcr die Installation von manuellen oder automatischen Etikettierwaagen (Preisauszeichnungswaagen) aller wichtigen Marken auf dem Markt ausgestattet.<\/p>\n<p>Alle Elixa\u00ae-Maschinen sind konform mit der Maschinenrichtlinie der Europ\u00e4ischen Union.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;50px&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;14804&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/elixa-14\/&#8220;]\n<h3><strong>Elixa 14<\/strong><\/h3>\n<div class=\"wrap_description_box\">Die Elixa 14 ist das Einstiegsmodell unter den Elixa-Verpackungsmaschinen mit Super-Stretch-Technologie, ideal f\u00fcr alle, die von der manuellen zur automatischen Verpackung wechseln m\u00f6chten.<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;14808&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/elixa-21\/&#8220;]\n<h3><strong>Elixa 21<\/strong><\/h3>\n<div class=\"wrap_description_box\">Elixa 21 ist die &#8222;Elixa&#8220;-Stretchpackung mit frontalem Ausgang, ideal f\u00fcr die Verpackung von frischen und sehr frischen Lebensmitteln.<\/div>\n[\/fancy_box][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;14812&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/elixa-24\/&#8220;]\n<h3><strong>Elixa 24<\/strong><\/h3>\n<div class=\"wrap_description_box\">Elixa 24 nutzt die &#8222;Elixa&#8220;-Superstretch-Technologie, um Fleisch, Fisch, Obst, Gem\u00fcse und Gastronomieprodukte automatisch, einfach und schnell zu verpacken.<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;14820&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/elixa-35\/&#8220;]\n<h3><strong>Elixa 35<\/strong><\/h3>\n<div class=\"wrap_description_box\">Die Elixa 35 ist die produktivste automatische Verpackungsmaschine der &#8222;Elixa&#8220;-Serie und eignet sich f\u00fcr mittelgro\u00dfe Verpackungszentren und Verkaufsstellen.<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;9315&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/elixa-30l\/&#8220;]\n<h3><strong>Elixa 30<sup>L<\/sup><\/strong><\/h3>\n<div class=\"wrap_description_box\">Elixa 30<sup>L<\/sup> ist die automatische Stretchverpackungsmaschine der Serie &#8222;Elixa&#8220;, die speziell f\u00fcr die Verpackung von gro\u00dfen und familiengro\u00dfen Schalen im Einzelhandel und in der Lebensmittelindustrie entwickelt wurde.<\/div>\n[\/fancy_box][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ffffff&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; id=&#8220;row_automac&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-10-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color=&#8220;#f4f4f4&#8243; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220;][nectar_animated_title heading_tag=&#8220;h2&#8243; style=&#8220;hinge-drop&#8220; color=&#8220;Accent-Color&#8220; text=&#8220;Automac\u00ae-Verpackungsmaschinen&#8220;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8220;.vc_custom_1644263587574{margin-top: 30px !important;}&#8220;]Automac\u00ae-Verpackungsmaschinen sind die ideale L\u00f6sung f\u00fcr die Hochgeschwindigkeitsverpackung von Lebensmitteln und die kontinuierliche Produktion. Sie sind \u00e4u\u00dferst zuverl\u00e4ssig und garantieren die perfekte Verpackung aller frischen und ultrafrischen Lebensmittel, wie Fleisch, Gefl\u00fcgel, pflanzliches Eiwei\u00df, Obst, Gem\u00fcse, K\u00e4se, Fisch, Brot, Geb\u00e4ck&#8230;<\/p>\n<p>Die Automac\u00ae-Verpackungsmaschinen verwenden die wichtigsten auf dem Markt erh\u00e4ltlichen Stretchfolien, aber dank der historischen Erfahrung der Gruppo Fabbri in der Herstellung von Verpackungsmaschinen und Lebensmittelfolien k\u00f6nnen sie mit den Stretchfolien der Gruppe in neutraler und bedruckter Form optimale Leistungen und Einsparungen erzielen.<\/p>\n<p>Unsere Designer stehen dem Kunden f\u00fcr die Erstellung von individuellen Drucken und Grafiken zur Verf\u00fcgung, die in Zusammenarbeit mit oder nach den Vorgaben des Kunden f\u00fcr eine bessere Produktkommunikation und -vermarktung erstellt werden k\u00f6nnen.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;10790&#8243; background_image_position=&#8220;center center&#8220; enable_bg_scale=&#8220;true&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;15417&#8243; background_image_position=&#8220;center center&#8220; enable_bg_scale=&#8220;true&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-10-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220;][vc_column_text css=&#8220;.vc_custom_1734443588669{margin-top: 30px !important;}&#8220;]Die Verwendung bedruckter Folien bietet n\u00e4mlich zus\u00e4tzliche Kommunikations- und Markenbildungsm\u00f6glichkeiten und verbessert in einigen F\u00e4llen das Erscheinungsbild verpackter Lebensmittel, indem sie die Verpackung sichtbarer und einladender macht, wenn sie am Verkaufsort ausgestellt wird. Alle Automac\u00ae-Maschinen sind konform mit der Maschinenrichtlinie der Europ\u00e4ischen Union.<br \/>\nAutomac Dual, Automac Industrial und Automac Ultra sind Teil der Fabbri Hybrid Familie von Maschinen f\u00fcr die Verpackung von frischen und Verpackung von frischen und ultrafrischen Produkten mit jeder Art von Schale und jeder Art von Stretchfolie (traditionelle, biobasierte, kompostierbare Folie). Zusammen mit Nature Fresh, der weltweit ersten zertifizierten kompostierbaren Folie ihrer Kategorie, hat das Projekt Fabbri Hybrid eine Anerkennung durch das Programm Horizont 2020 der Europ\u00e4ischen Union f\u00fcr Forschung und Innovation erhalten.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;50px&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;11166&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/automac-dual\/&#8220;]\n<h3><strong> Automac Dual <\/strong><\/h3>\n<div class=\"wrap_description_box\">Unter Beibehaltung des f\u00fcr den Automac 40 typischen Zwei-Rollen-Betriebs verpackt der Automac Dual alle Arten von Materialien und f\u00fchrt einen neuen Leistungsstandard f\u00fcr Leistung und Konnektivit\u00e4t ein, der die Anforderungen der INDUSTRIE 4.0 erf\u00fcllt.<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;11146&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/automac-industrial\/&#8220;]\n<h3><strong> Automac Industrial <\/strong><\/h3>\n<div class=\"wrap_description_box\">Abgeleitet von Automac 55 Pi\u00f9, verpackt Automac Industrial mit jeder Art von Folie und Schale und f\u00fchrt neue Leistungsstandards im Einklang mit INDUSTRIE 4.0 ein.<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;11152&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/automac-ultra\/&#8220;]\n<h3><strong> Automac Ultra <\/strong><\/h3>\n<div class=\"wrap_description_box\">Unter Beibehaltung der typischen Merkmale von Automac 75 kann Automac Ultra traditionelle, biobasierte oder<br \/>\nkompostierbare Materialien f\u00fcr die Verpackung verwenden. Es ist nach den Anforderungen von INDUSTRIA 4.0 konzipiert und kann daher an betriebliche ERP- und MES-Systeme angeschlossen werden.<\/div>\n[\/fancy_box][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;11162&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/automac-40\/&#8220;]\n<h3><strong>Automac 40<\/strong><\/h3>\n<div class=\"wrap_description_box\">Automac 40 ist die Doppelrollenverpackungsmaschine, die die unterschiedlichen Produktionsanforderungen der<br \/>\nLebensmittelindustrie mit maximaler Flexibilit\u00e4t erf\u00fcllt.<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;11155&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/automac-55-piu\/&#8220;]\n<h3><strong> Automac 55 Pi\u00f9 <\/strong><\/h3>\n<div class=\"wrap_description_box\">Die Automac 55 Pi\u00f9 ist das Flaggschiff unter den automatischen Stretchverpackungsmaschinen und die ideale Wahl f\u00fcr alle, die hohe Produktivit\u00e4t und maximale Zuverl\u00e4ssigkeit verlangen.<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;11143&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/automac-75\/&#8220;]\n<h3><strong> Automac 75<\/strong><\/h3>\n<div class=\"wrap_description_box\">Zusammen mit Automac 95 ist Automac 75 die Antwort auf die st\u00e4ndig steigenden Anforderungen an die Leistungsf\u00e4higkeit von Verpackungszentren und Industrie.<\/div>\n[\/fancy_box][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;11140&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/macchine-confezionamento\/avvolgitrici-automatiche\/automac-95\/&#8220;]\n<h3><strong> Automac 95<\/strong><\/h3>\n<div class=\"wrap_description_box\">Die Automac 95 ist die schnellste automatische und zuverl\u00e4ssige Stretchverpackungsmaschine der Gruppo Fabbri (bis zu 90 ppm, mit einstellbaren Parametern je nach den spezifischen Produktionsanforderungen).<\/div>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;10826&#8243; bg_position=&#8220;left center&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;10%&#8220; bottom_padding=&#8220;10%&#8220; text_color=&#8220;light&#8220;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":12686,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12718","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Automatische Lebensmittelverpackungsmaschinen<\/title>\n<meta name=\"description\" content=\"Automatische Stretchverpackungsmaschinen f\u00fcr frische Lebensmittel. Schnell, sicher und effizient. Jetzt mehr erfahren!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Automatische Lebensmittelverpackungsmaschinen\" \/>\n<meta property=\"og:description\" content=\"Automatische Stretchverpackungsmaschinen f\u00fcr frische Lebensmittel. Schnell, sicher und effizient. Jetzt mehr erfahren!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Fabbri | Official WebSite\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T07:49:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/verpackungsmaschinen\\\/automatische-stretchverpackungsmaschinen\\\/\",\"url\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/verpackungsmaschinen\\\/automatische-stretchverpackungsmaschinen\\\/\",\"name\":\"Automatische Lebensmittelverpackungsmaschinen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/#website\"},\"datePublished\":\"2021-06-04T14:52:39+00:00\",\"dateModified\":\"2025-08-29T07:49:43+00:00\",\"description\":\"Automatische Stretchverpackungsmaschinen f\u00fcr frische Lebensmittel. Schnell, sicher und effizient. Jetzt mehr erfahren!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/verpackungsmaschinen\\\/automatische-stretchverpackungsmaschinen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/verpackungsmaschinen\\\/automatische-stretchverpackungsmaschinen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/verpackungsmaschinen\\\/automatische-stretchverpackungsmaschinen\\\/#breadcrumb\",\"itemListElement\":[]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/\",\"name\":\"Gruppo Fabbri | Official WebSite\",\"description\":\"Macchine e Film per l&#039;imballaggio e confezionamento alimentare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Automatische Lebensmittelverpackungsmaschinen","description":"Automatische Stretchverpackungsmaschinen f\u00fcr frische Lebensmittel. Schnell, sicher und effizient. Jetzt mehr erfahren!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/","og_locale":"de_DE","og_type":"article","og_title":"Automatische Lebensmittelverpackungsmaschinen","og_description":"Automatische Stretchverpackungsmaschinen f\u00fcr frische Lebensmittel. Schnell, sicher und effizient. Jetzt mehr erfahren!","og_url":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/","og_site_name":"Gruppo Fabbri | Official WebSite","article_modified_time":"2025-08-29T07:49:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/","url":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/","name":"Automatische Lebensmittelverpackungsmaschinen","isPartOf":{"@id":"https:\/\/www.gruppofabbri.com\/de\/#website"},"datePublished":"2021-06-04T14:52:39+00:00","dateModified":"2025-08-29T07:49:43+00:00","description":"Automatische Stretchverpackungsmaschinen f\u00fcr frische Lebensmittel. Schnell, sicher und effizient. Jetzt mehr erfahren!","breadcrumb":{"@id":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gruppofabbri.com\/de\/produkte\/verpackungsmaschinen\/automatische-stretchverpackungsmaschinen\/#breadcrumb","itemListElement":[]},{"@type":"WebSite","@id":"https:\/\/www.gruppofabbri.com\/de\/#website","url":"https:\/\/www.gruppofabbri.com\/de\/","name":"Gruppo Fabbri | Official WebSite","description":"Macchine e Film per l&#039;imballaggio e confezionamento alimentare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gruppofabbri.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/12718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/comments?post=12718"}],"version-history":[{"count":4,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/12718\/revisions"}],"predecessor-version":[{"id":28855,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/12718\/revisions\/28855"}],"up":[{"embeddable":true,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/12686"}],"wp:attachment":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/media?parent=12718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}