{"id":12618,"date":"2021-06-04T17:22:29","date_gmt":"2021-06-04T15:22:29","guid":{"rendered":"https:\/\/www.gruppofabbri.com\/pellicole-compostabili-biobased\/"},"modified":"2026-06-08T09:56:33","modified_gmt":"2026-06-08T07:56:33","slug":"biobased-und-kompostierbare-folien","status":"publish","type":"page","link":"https:\/\/www.gruppofabbri.com\/de\/produkte\/folien-zum-schutz\/biobased-und-kompostierbare-folien\/","title":{"rendered":"Pellicole compostabili e biobased"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;11206&#8243; bg_position=&#8220;left center&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;10%&#8220; bottom_padding=&#8220;10%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#012169&#8243; overlay_strength=&#8220;1&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; parallax_bg=&#8220;true&#8220; parallax_bg_speed=&#8220;fast&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/12&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][nectar_highlighted_text color_type=&#8220;regular&#8220; highlight_color=&#8220;#1dafec&#8220; style=&#8220;half_text&#8220; custom_font_size=&#8220;48px&#8220;]\n<h1>Biobased und Kompostierbare<br \/>\nFolien<\/h1>\n[\/nectar_highlighted_text][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8220;Full Width Line&#8220; line_thickness=&#8220;1&#8243; divider_color=&#8220;default&#8220; custom_height=&#8220;100&#8243;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;7\/12&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;40px&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; centered_text=&#8220;true&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_custom_heading text=&#8220;Entdecke unsere Biokunststoff-Folien&#8220; font_container=&#8220;tag:h3|text_align:center&#8220; use_theme_fonts=&#8220;yes&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;15279&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/biobased-star-film\/&#8220;]\n<h3><strong>Biobased Star Film<\/strong><\/h3>\n<p>&#8222;OK-biobased<sup>\u00ae<\/sup>&#8222;-zertifizierte Stretchfolie vom T\u00dcV Austria. Druckbar.[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;15283&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/nature-fresh\/&#8220;]\n<h3><strong>Nature Fresh<\/strong><\/h3>\n<p>Die zertifizierte kompostierbare Folie f\u00fcr die automatische und manuelle Verpackung aller Arten von Lebensmitteln. Druckbar. Auch in Ho.Re.Ca.-Kutterboxen erh\u00e4ltlich.[\/fancy_box][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;15279&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/produkte\/folien-zum-schutz\/barrierefolien\/nature-lid\/&#8220;]\n<h3><strong>Nature Lid<\/strong><\/h3>\n<p>Der zertifizierte kompostierbare Deckelfilm f\u00fcr die Lebensmittelverpackung in W\u00e4rmeversiegelung und modifizierter Atmosph\u00e4renverpackung (MAP\/ATP).[\/fancy_box][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][fancy_box box_style=&#8220;default&#8220; icon_family=&#8220;none&#8220; image_url=&#8220;33380&#8243; color=&#8220;accent-color&#8220; border_radius=&#8220;default&#8220; image_loading=&#8220;default&#8220; link_url=&#8220;\/de\/prodotti\/film-e-pellicole\/film-stretch\/perflex\/&#8220;]\n<h3><strong>PER<em>flex<\/em><\/strong><\/h3>\n<p>Die 100 % recycelbare PE-Stretchfolie aus Monomaterial, die entwickelt wurde, um den \u00dcbergang zu PPWR-konformen Verpackungsl\u00f6sungen zu unterst\u00fctzen.[\/fancy_box][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;11206&#8243; bg_position=&#8220;left center&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;10%&#8220; bottom_padding=&#8220;10%&#8220; text_color=&#8220;light&#8220;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":12622,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12618","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pellicole compostabili e biobased - Gruppo Fabbri | Official WebSite<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gruppofabbri.com\/de\/produkte\/folien-zum-schutz\/biobased-und-kompostierbare-folien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pellicole compostabili e biobased - Gruppo Fabbri | Official WebSite\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;11206&#8243; bg_position=&#8220;left center&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;10%&#8220; bottom_padding=&#8220;10%&#8220; text_color=&#8220;light&#8220;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gruppofabbri.com\/de\/produkte\/folien-zum-schutz\/biobased-und-kompostierbare-folien\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo Fabbri | Official WebSite\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T07:56:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/folien-zum-schutz\\\/biobased-und-kompostierbare-folien\\\/\",\"url\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/folien-zum-schutz\\\/biobased-und-kompostierbare-folien\\\/\",\"name\":\"Pellicole compostabili e biobased - Gruppo Fabbri | Official WebSite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/#website\"},\"datePublished\":\"2021-06-04T15:22:29+00:00\",\"dateModified\":\"2026-06-08T07:56:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/folien-zum-schutz\\\/biobased-und-kompostierbare-folien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/folien-zum-schutz\\\/biobased-und-kompostierbare-folien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/produkte\\\/folien-zum-schutz\\\/biobased-und-kompostierbare-folien\\\/#breadcrumb\",\"itemListElement\":[]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/\",\"name\":\"Gruppo Fabbri | Official WebSite\",\"description\":\"Macchine e Film per l&#039;imballaggio e confezionamento alimentare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gruppofabbri.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pellicole compostabili e biobased - Gruppo Fabbri | Official WebSite","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gruppofabbri.com\/de\/produkte\/folien-zum-schutz\/biobased-und-kompostierbare-folien\/","og_locale":"de_DE","og_type":"article","og_title":"Pellicole compostabili e biobased - Gruppo Fabbri | Official WebSite","og_description":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;11206&#8243; bg_position=&#8220;left center&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;10%&#8220; bottom_padding=&#8220;10%&#8220; text_color=&#8220;light&#8220;...","og_url":"https:\/\/www.gruppofabbri.com\/de\/produkte\/folien-zum-schutz\/biobased-und-kompostierbare-folien\/","og_site_name":"Gruppo Fabbri | Official WebSite","article_modified_time":"2026-06-08T07:56:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gruppofabbri.com\/de\/produkte\/folien-zum-schutz\/biobased-und-kompostierbare-folien\/","url":"https:\/\/www.gruppofabbri.com\/de\/produkte\/folien-zum-schutz\/biobased-und-kompostierbare-folien\/","name":"Pellicole compostabili e biobased - Gruppo Fabbri | Official WebSite","isPartOf":{"@id":"https:\/\/www.gruppofabbri.com\/de\/#website"},"datePublished":"2021-06-04T15:22:29+00:00","dateModified":"2026-06-08T07:56:33+00:00","breadcrumb":{"@id":"https:\/\/www.gruppofabbri.com\/de\/produkte\/folien-zum-schutz\/biobased-und-kompostierbare-folien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gruppofabbri.com\/de\/produkte\/folien-zum-schutz\/biobased-und-kompostierbare-folien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gruppofabbri.com\/de\/produkte\/folien-zum-schutz\/biobased-und-kompostierbare-folien\/#breadcrumb","itemListElement":[]},{"@type":"WebSite","@id":"https:\/\/www.gruppofabbri.com\/de\/#website","url":"https:\/\/www.gruppofabbri.com\/de\/","name":"Gruppo Fabbri | Official WebSite","description":"Macchine e Film per l&#039;imballaggio e confezionamento alimentare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gruppofabbri.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/12618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/comments?post=12618"}],"version-history":[{"count":11,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/12618\/revisions"}],"predecessor-version":[{"id":33444,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/12618\/revisions\/33444"}],"up":[{"embeddable":true,"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/pages\/12622"}],"wp:attachment":[{"href":"https:\/\/www.gruppofabbri.com\/de\/wp-json\/wp\/v2\/media?parent=12618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}